{"id":1419,"date":"2022-10-24T12:18:37","date_gmt":"2022-10-24T16:18:37","guid":{"rendered":"https:\/\/www.lewithin.com\/?page_id=1419"},"modified":"2024-09-19T16:49:32","modified_gmt":"2024-09-19T20:49:32","slug":"vie-de-communaute","status":"publish","type":"page","link":"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/","title":{"rendered":"La vie de communaut\u00e9"},"content":{"rendered":"\t\t\t<header  class=\"header-half-half section-block enter\" data-scroll-section data-colored-section=\"default-theme\" data-simple-module-animation data-animator-id=\"progress\">\n\t\t\t\t<div class=\"container text-container\">\n\t\t\t\t\t<div class=\"row content-row\">\n\t\t\t\t\t\t<div class=\"col-md-7 section-title\">\n\t\t\t\t\t\t\t<h1 class=\"title title-1\" data-split-texts=\"letters\">La vie au <em class=\"serif\">Le\u00a0Within<\/em>\n<\/h1>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"col-md-4 offset-md-1 content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-wrapper\">\n\t\t\t\t\t\t\t\t\t<p>Faites partie d\u2019une communaut\u00e9 inclusive qui a pour mission de mettre chaque personne en valeur, et d\u00e9couvrez diff\u00e9rents espaces d\u00e9di\u00e9s \u00e0 la r\u00e9alisation de projets qui vous passionnent.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btns\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btn-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<button \n\t\t\t\t\tclass=\"button button-primary \"\n\t\t\t\t\tdata-book-open\t\t\t\t>\n\t\t\t\t\t<span class=\"btn-mask\" data-button-label=\"Planifier une visite\">\n\t\t\t\t\t\t<span class=\"btn-text\">Planifier une visite<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/button>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"row images-row\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-4 col-sm-6 col-8 offset-md-1 offset-sm-3 offset-1 first img-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"img-mask\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"725\" src=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-580x725.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-580x725.jpg 580w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-240x300.jpg 240w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-819x1024.jpg 819w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-768x960.jpg 768w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-1229x1536.jpg 1229w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-1638x2048.jpg 1638w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-494x618.jpg 494w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-24x30.jpg 24w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-735x919.jpg 735w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-270x338.jpg 270w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-1820x2275.jpg 1820w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-110x138.jpg 110w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-745x931.jpg 745w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-1400x1750.jpg 1400w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-910x1138.jpg 910w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-425x531.jpg 425w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-1085x1356.jpg 1085w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-650x813.jpg 650w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/12\/Within4910-scaled.jpg 2048w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"col-md-3 col-sm-5 offset-md-3 offset-sm-7 col-6 offset-6 second img-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"img-mask\">\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"725\" src=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-580x725.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-580x725.jpg 580w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-240x300.jpg 240w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-819x1024.jpg 819w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-768x960.jpg 768w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-1229x1536.jpg 1229w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-1638x2048.jpg 1638w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-494x618.jpg 494w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-24x30.jpg 24w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-735x919.jpg 735w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-270x338.jpg 270w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-1820x2275.jpg 1820w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-110x138.jpg 110w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-745x931.jpg 745w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-1400x1750.jpg 1400w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-910x1138.jpg 910w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-425x531.jpg 425w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-1085x1356.jpg 1085w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-650x813.jpg 650w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/Within5487-scaled.jpg 2048w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/header>\n\t\t\n\n\t\t\t<section  class=\"half-half section-block enter\" data-scroll-section data-colored-section=\"default-theme\" data-simple-module-animation data-animator-id=\"progress\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"row half-half-row\">\n\t\t\t\t\t\t<div class=\"col-lg-5 col-md-6 half-content\">\n\t\t\t\t\t\t\t<h2 class=\"title title-3\" data-split-texts=\"\">\u00c0 d\u00e9couvrir<br \/>\n<em class=\"serif\">au Le\u00a0Within<\/em>\n<\/h2>\t\n\t\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t<div class=\"text-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p>En plus de proposer une cuisine dans chaque appartement, Le Within comprend une grande cuisine commune, une salle de jeux, un espace caf\u00e9 anim\u00e9, une salle d\u2019\u00e9tude de style biblioth\u00e8que, un studio o\u00f9 enregistrer vid\u00e9os et balados ainsi qu\u2019une salle \u00e9v\u00e9nementielle modulable.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"col-md-6 offset-lg-1 images-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"first img-wrapper\">\n\t\t\t\t\t\t\t\t\t<div class=\"img-mask\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"246\" height=\"129\" src=\"https:\/\/www.lewithin.com\/wp-content\/uploads\/2022\/08\/LW-2.svg\" class=\"\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"second img-wrapper\">\n\t\t\t\t\t\t\t\t\t<div class=\"img-mask\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"725\" src=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-580x725.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-580x725.jpg 580w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-240x300.jpg 240w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-819x1024.jpg 819w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-768x960.jpg 768w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-1229x1536.jpg 1229w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-1638x2048.jpg 1638w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-494x618.jpg 494w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-24x30.jpg 24w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-735x919.jpg 735w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-270x338.jpg 270w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-1820x2275.jpg 1820w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-110x138.jpg 110w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-745x931.jpg 745w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-1400x1750.jpg 1400w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-910x1138.jpg 910w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-425x531.jpg 425w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-1085x1356.jpg 1085w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-650x813.jpg 650w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5207-scaled.jpg 2048w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"third img-wrapper\">\n\t\t\t\t\t\t\t\t\t<div class=\"img-mask\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"580\" height=\"725\" src=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-580x725.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-580x725.jpg 580w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-240x300.jpg 240w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-819x1024.jpg 819w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-768x960.jpg 768w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-1229x1536.jpg 1229w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-1638x2048.jpg 1638w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-494x618.jpg 494w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-24x30.jpg 24w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-735x919.jpg 735w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-270x338.jpg 270w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-1820x2275.jpg 1820w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-110x138.jpg 110w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-745x931.jpg 745w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-1400x1750.jpg 1400w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-910x1138.jpg 910w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-425x531.jpg 425w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-1085x1356.jpg 1085w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-650x813.jpg 650w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/01\/Within5279-scaled.jpg 2048w\" sizes=\"(max-width: 580px) 100vw, 580px\" \/>\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\n\t\t\t<section  class=\"cta-block enter\" data-scroll-section data-colored-section=\"asphalt-theme\" data-simple-module-animation data-module-threshold=\"0.5\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t<div class=\"col-lg-8 offset-lg-2 col-sm-10 offset-sm-1\">\n\t\t\t\t\t\t\t<div class=\"content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"title\" data-split-texts>\n\t\t\t\t\t\t\t\t\t\tSoyez l\u2019architecte de votre propre aventure. \u00c9crivez votre histoire au Le&nbsp;Within.\n\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btns\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btn-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lewithin.com\/fr\/residences-etudiantes-montreal\/\" \n\t\t\t\t\tclass=\"button button-primary \" \n\t\t\t\t\t \n\t\t\t\t\t>\n\t\t\t\t\t<span class=\"btn-mask\" data-button-label=\"D\u00e9couvrez nos espaces enti\u00e8rement meubl\u00e9s\">\n\t\t\t\t\t\t<span class=\"btn-text\">D\u00e9couvrez nos espaces enti\u00e8rement meubl\u00e9s<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\n\t\t\t<section  class=\"half-title-half-list\" data-scroll-section data-colored-section=\"default-theme\" data-animator-id=\"progressInScreen\">\n\t\t\t\t<div class=\"container half-title-half-list-ctn\" style=\"--items: 8\">\n\t\t\t\t\t<div class=\"row half-half-row enter\" data-simple-module-animation>\n\t\t\t\t\t\t<div class=\"col-lg-6 col-md-5\">\n\t\t\t\t\t\t\t<div class=\"section-title\" data-sticky=\"top\" data-sticky-no-offset>\n\t\t\t\t\t\t\t\t<h2 class=\"title title-2\" data-split-texts=\"\">\u00c0 d\u00e9couvrir dans les environs\n<\/h2>\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"col-lg-6 col-md-7 list-items\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item\" style=\"--i: 1\">\n\t\t\t\t\t\t\t\t\t<div class=\"item-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<p class=\"title-4\">Ville souterraine<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item\" style=\"--i: 2\">\n\t\t\t\t\t\t\t\t\t<div class=\"item-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<p class=\"title-4\">Parcs et mont Royal<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item\" style=\"--i: 3\">\n\t\t\t\t\t\t\t\t\t<div class=\"item-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<p class=\"title-4\">March\u00e9s gastronomiques et halles gourmandes<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item\" style=\"--i: 4\">\n\t\t\t\t\t\t\t\t\t<div class=\"item-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<p class=\"title-4\">Restaurants branch\u00e9s aux saveurs du monde entier<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item\" style=\"--i: 5\">\n\t\t\t\t\t\t\t\t\t<div class=\"item-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<p class=\"title-4\">Mus\u00e9es et galeries d\u2019art<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item\" style=\"--i: 6\">\n\t\t\t\t\t\t\t\t\t<div class=\"item-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<p class=\"title-4\">Centres commerciaux et boutiques<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item\" style=\"--i: 7\">\n\t\t\t\t\t\t\t\t\t<div class=\"item-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<p class=\"title-4\">Cin\u00e9mas et th\u00e9\u00e2tres<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"item\" style=\"--i: 8\">\n\t\t\t\t\t\t\t\t\t<div class=\"item-wrapper\">\n\t\t\t\t\t\t\t\t\t\t<p class=\"title-4\">Caf\u00e9s troisi\u00e8me vague<\/p>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\n\t\t\t<section  class=\"blog-latest-articles section-block\" data-scroll-section data-colored-section=\"light-theme\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t<div class=\"col-md-12 section-title enter\" data-simple-module-animation>\n\t\t\t\t\t\t\t<h2 class=\"title title-3\" data-split-texts>R\u00e9cents <em class=\"serif\">Articles<\/em>\n<\/h2>\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btns\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btn-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lewithin.com\/fr\/blogue\/\" \n\t\t\t\t\tclass=\"button button-primary \" \n\t\t\t\t\t \n\t\t\t\t\t>\n\t\t\t\t\t<span class=\"btn-mask\" data-button-label=\"Voir tous nos articles\">\n\t\t\t\t\t\t<span class=\"btn-text\">Voir tous nos articles<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"col-md-12 latest-articles blog-article-cards enter\" data-simple-module-animation data-module-threshold=\"0.2\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n<article class=\"article-card accent-theme-inverted\" style=\"--idx: 0\">\n\t<a href=\"https:\/\/www.lewithin.com\/fr\/blogue\/non-classifiee\/etudiant-international-a-montreal-4-choses-a-savoir\/\" class=\"article-card-link\" aria-label=\"Lire l'article\">\n\t\t<div class=\"image-container\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-650x650.jpg\" class=\"image\" alt=\"\" srcset=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-650x650.jpg 650w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-300x300.jpg 300w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-1024x1024.jpg 1024w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-150x150.jpg 150w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-768x768.jpg 768w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-1536x1536.jpg 1536w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-618x618.jpg 618w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-30x30.jpg 30w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-735x735.jpg 735w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-580x580.jpg 580w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-270x270.jpg 270w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-110x110.jpg 110w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-745x745.jpg 745w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-1400x1400.jpg 1400w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-910x910.jpg 910w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-425x425.jpg 425w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3-1085x1085.jpg 1085w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article3.jpg 1780w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t<\/div>\n\t\t<div class=\"text\">\n\t\t\t<p class=\"upper-title uppercase\">Guide et astuces<\/p>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"title title-5\">\u00c9tudiant international \u00e0 Montr\u00e9al: 4 choses \u00e0 savoir<\/h3>\t\t\t\t\t\t<svg \n\t\t\t class=\"arrow\"\t\t\tviewBox=\"0 0 36 45\" width=\"36\" height=\"45\">\n\t\t\t<path d=\"m0 26.781 3.89-4.089 11.246 11.477V0h5.658v34.169L32.11 22.62 36 26.709 17.965 45z\" fill-rule=\"nonzero\"\/>\n\t\t<\/svg>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n<article class=\"article-card accent-theme-inverted\" style=\"--idx: 1\">\n\t<a href=\"https:\/\/www.lewithin.com\/fr\/blogue\/non-classifiee\/les-7-raisons-qui-font-de-montreal-la-meilleure-ville-etudiante-au-monde\/\" class=\"article-card-link\" aria-label=\"Lire l'article\">\n\t\t<div class=\"image-container\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-650x650.jpg\" class=\"image\" alt=\"\" srcset=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-650x650.jpg 650w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-300x300.jpg 300w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-1024x1024.jpg 1024w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-150x150.jpg 150w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-768x768.jpg 768w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-1536x1536.jpg 1536w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-618x618.jpg 618w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-30x30.jpg 30w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-735x735.jpg 735w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-580x580.jpg 580w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-270x270.jpg 270w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-110x110.jpg 110w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-745x745.jpg 745w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-1400x1400.jpg 1400w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-910x910.jpg 910w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-425x425.jpg 425w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2-1085x1085.jpg 1085w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article2.jpg 1780w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t<\/div>\n\t\t<div class=\"text\">\n\t\t\t<p class=\"upper-title uppercase\">Mode de vie<\/p>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"title title-5\">Les 7 raisons qui font de Montr\u00e9al la meilleure ville \u00e9tudiante au monde<\/h3>\t\t\t\t\t\t<svg \n\t\t\t class=\"arrow\"\t\t\tviewBox=\"0 0 36 45\" width=\"36\" height=\"45\">\n\t\t\t<path d=\"m0 26.781 3.89-4.089 11.246 11.477V0h5.658v34.169L32.11 22.62 36 26.709 17.965 45z\" fill-rule=\"nonzero\"\/>\n\t\t<\/svg>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n<article class=\"article-card accent-theme-inverted\" style=\"--idx: 2\">\n\t<a href=\"https:\/\/www.lewithin.com\/fr\/blogue\/non-classifiee\/trouver-une-residence-etudiante-a-montreal-le-guide\/\" class=\"article-card-link\" aria-label=\"Lire l'article\">\n\t\t<div class=\"image-container\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"650\" height=\"650\" src=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-650x650.jpg\" class=\"image\" alt=\"\" srcset=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-650x650.jpg 650w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-300x300.jpg 300w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-1024x1024.jpg 1024w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-150x150.jpg 150w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-768x768.jpg 768w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-1536x1536.jpg 1536w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-618x618.jpg 618w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-30x30.jpg 30w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-735x735.jpg 735w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-580x580.jpg 580w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-270x270.jpg 270w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-110x110.jpg 110w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-745x745.jpg 745w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-1400x1400.jpg 1400w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-910x910.jpg 910w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-425x425.jpg 425w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1-1085x1085.jpg 1085w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2023\/06\/article_1.jpg 1780w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/>\t\t\t\t\t<\/div>\n\t\t<div class=\"text\">\n\t\t\t<p class=\"upper-title uppercase\">Guide et astuces<\/p>\n\t\t\t<div class=\"title-wrapper\">\n\t\t\t\t<h3 class=\"title title-5\">Trouver une r\u00e9sidence \u00e9tudiante \u00e0 Montr\u00e9al<\/h3>\t\t\t\t\t\t<svg \n\t\t\t class=\"arrow\"\t\t\tviewBox=\"0 0 36 45\" width=\"36\" height=\"45\">\n\t\t\t<path d=\"m0 26.781 3.89-4.089 11.246 11.477V0h5.658v34.169L32.11 22.62 36 26.709 17.965 45z\" fill-rule=\"nonzero\"\/>\n\t\t<\/svg>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/a>\n<\/article>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\n\t\t\t<section  class=\"map section-block is-inverted\" data-scroll-section data-colored-section=\"default-theme\">\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"row map-row\">\n\t\t\t\t\t\t<div class=\"col-md-5 half-text lines enter\" data-simple-module-animation>\n\t\t\t\t\t\t\t<h2 class=\"title title-3\" data-split-texts=\"\">Situ\u00e9 au centre-ville de <span class=\"serif\">Montr\u00e9al<\/span>\n<\/h2>\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"text-wrapper\">\n\t\t\t\t\t\t\t\t\t<p>Le Within est l\u2019endroit parfait o\u00f9 r\u00e9aliser votre plein potentiel dans un environnement \u00e0 votre image. Passez des \u00e9tudes aux loisirs en laissant libre cours \u00e0 votre imagination et profitez d\u2019une programmation ax\u00e9e sur vos passions.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btns\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btn-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lewithin.com\/fr\/contact\/\" \n\t\t\t\t\tclass=\"button button-primary \" \n\t\t\t\t\t \n\t\t\t\t\t>\n\t\t\t\t\t<span class=\"btn-mask\" data-button-label=\"Nous joindre\">\n\t\t\t\t\t\t<span class=\"btn-text\">Nous joindre<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"col-md-7 map-wrapper enter\" data-simple-module-animation>\n\t\t\t\t\t\t\t<div class=\"google-map\" data-google-map><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t\n\n\t\t\t<section  class=\"boxed-half-half enter\" data-scroll-section data-colored-section=\"default-theme\" data-simple-module-animation>\n\t\t\t\t<div class=\"container\">\n\t\t\t\t\t<div class=\"row\">\n\t\t\t\t\t\t<div class=\"col-md-6 left-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t\t<p class=\"title\" data-split-texts>\n\t\t\t\t\t\t\t\t\t\tVous avez des questions?\n\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"bg\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"910\" height=\"860\" src=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-910x860.jpg\" class=\"\" alt=\"\" srcset=\"https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-910x860.jpg 910w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-300x284.jpg 300w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-1024x968.jpg 1024w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-768x726.jpg 768w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-1536x1452.jpg 1536w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-654x618.jpg 654w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-32x30.jpg 32w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-735x695.jpg 735w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-580x548.jpg 580w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-270x255.jpg 270w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-110x104.jpg 110w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-745x704.jpg 745w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-1400x1323.jpg 1400w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-425x402.jpg 425w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community-1085x1025.jpg 1085w, https:\/\/s3.ca-central-1.amazonaws.com\/cdn.lewithin.com\/wp-content\/uploads\/2022\/11\/questions_community.jpg 1820w\" sizes=\"(max-width: 910px) 100vw, 910px\" \/>\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"col-md-6 right-content accent-theme\">\n\t\t\t\t\t\t\t<div class=\"right-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"title title-3\" data-split-texts=\"\">Nous sommes&nbsp;l\u00e0 <span class=\"serif\">pour vous aider.<\/span>\n<\/h2>\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btns\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"btn-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.lewithin.com\/fr\/contact\/\" \n\t\t\t\t\tclass=\"button button-primary \" \n\t\t\t\t\t \n\t\t\t\t\t>\n\t\t\t\t\t<span class=\"btn-mask\" data-button-label=\"Nous joindre\">\n\t\t\t\t\t\t<span class=\"btn-text\">Nous joindre<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/section>\n\t\t","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":11,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La vie de communaut\u00e9 - Le Within<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez la vie de communaut\u00e9 du Within. Situ\u00e9e au coeur de Montr\u00e9al, notre r\u00e9sidence \u00e9tudiante est un lieu de rencontres, d&#039;\u00e9tudes et de partage pour les \u00e9tudiants internationaux.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La vie de communaut\u00e9 - Le Within\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez la vie de communaut\u00e9 du Within. Situ\u00e9e au coeur de Montr\u00e9al, notre r\u00e9sidence \u00e9tudiante est un lieu de rencontres, d&#039;\u00e9tudes et de partage pour les \u00e9tudiants internationaux.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/\" \/>\n<meta property=\"og:site_name\" content=\"Le Within\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/le.within\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-19T20:49:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lewithin.com\/wp-content\/uploads\/2022\/09\/LW-OGImage.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/\",\"url\":\"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/\",\"name\":\"La vie de communaut\u00e9 - Le Within\",\"isPartOf\":{\"@id\":\"https:\/\/www.lewithin.com\/fr\/#website\"},\"datePublished\":\"2022-10-24T16:18:37+00:00\",\"dateModified\":\"2024-09-19T20:49:32+00:00\",\"description\":\"D\u00e9couvrez la vie de communaut\u00e9 du Within. Situ\u00e9e au coeur de Montr\u00e9al, notre r\u00e9sidence \u00e9tudiante est un lieu de rencontres, d'\u00e9tudes et de partage pour les \u00e9tudiants internationaux.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.lewithin.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La vie de communaut\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lewithin.com\/fr\/#website\",\"url\":\"https:\/\/www.lewithin.com\/fr\/\",\"name\":\"Le Within\",\"description\":\"Lofts \u00e9tudiants, Montr\u00e9al\",\"publisher\":{\"@id\":\"https:\/\/www.lewithin.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lewithin.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lewithin.com\/fr\/#organization\",\"name\":\"Le Within\",\"url\":\"https:\/\/www.lewithin.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lewithin.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lewithin.com\/wp-content\/uploads\/2022\/09\/LW-OGImage.png\",\"contentUrl\":\"https:\/\/www.lewithin.com\/wp-content\/uploads\/2022\/09\/LW-OGImage.png\",\"width\":1200,\"height\":630,\"caption\":\"Le Within\"},\"image\":{\"@id\":\"https:\/\/www.lewithin.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/le.within\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La vie de communaut\u00e9 - Le Within","description":"D\u00e9couvrez la vie de communaut\u00e9 du Within. Situ\u00e9e au coeur de Montr\u00e9al, notre r\u00e9sidence \u00e9tudiante est un lieu de rencontres, d'\u00e9tudes et de partage pour les \u00e9tudiants internationaux.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/","og_locale":"fr_FR","og_type":"article","og_title":"La vie de communaut\u00e9 - Le Within","og_description":"D\u00e9couvrez la vie de communaut\u00e9 du Within. Situ\u00e9e au coeur de Montr\u00e9al, notre r\u00e9sidence \u00e9tudiante est un lieu de rencontres, d'\u00e9tudes et de partage pour les \u00e9tudiants internationaux.","og_url":"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/","og_site_name":"Le Within","article_publisher":"https:\/\/www.facebook.com\/le.within","article_modified_time":"2024-09-19T20:49:32+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.lewithin.com\/wp-content\/uploads\/2022\/09\/LW-OGImage.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/","url":"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/","name":"La vie de communaut\u00e9 - Le Within","isPartOf":{"@id":"https:\/\/www.lewithin.com\/fr\/#website"},"datePublished":"2022-10-24T16:18:37+00:00","dateModified":"2024-09-19T20:49:32+00:00","description":"D\u00e9couvrez la vie de communaut\u00e9 du Within. Situ\u00e9e au coeur de Montr\u00e9al, notre r\u00e9sidence \u00e9tudiante est un lieu de rencontres, d'\u00e9tudes et de partage pour les \u00e9tudiants internationaux.","breadcrumb":{"@id":"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lewithin.com\/fr\/vie-de-communaute\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lewithin.com\/fr\/"},{"@type":"ListItem","position":2,"name":"La vie de communaut\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.lewithin.com\/fr\/#website","url":"https:\/\/www.lewithin.com\/fr\/","name":"Le Within","description":"Lofts \u00e9tudiants, Montr\u00e9al","publisher":{"@id":"https:\/\/www.lewithin.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lewithin.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lewithin.com\/fr\/#organization","name":"Le Within","url":"https:\/\/www.lewithin.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lewithin.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.lewithin.com\/wp-content\/uploads\/2022\/09\/LW-OGImage.png","contentUrl":"https:\/\/www.lewithin.com\/wp-content\/uploads\/2022\/09\/LW-OGImage.png","width":1200,"height":630,"caption":"Le Within"},"image":{"@id":"https:\/\/www.lewithin.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/le.within"]}]}},"_links":{"self":[{"href":"https:\/\/www.lewithin.com\/fr\/wp-json\/wp\/v2\/pages\/1419"}],"collection":[{"href":"https:\/\/www.lewithin.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.lewithin.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.lewithin.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lewithin.com\/fr\/wp-json\/wp\/v2\/comments?post=1419"}],"version-history":[{"count":5,"href":"https:\/\/www.lewithin.com\/fr\/wp-json\/wp\/v2\/pages\/1419\/revisions"}],"predecessor-version":[{"id":3414,"href":"https:\/\/www.lewithin.com\/fr\/wp-json\/wp\/v2\/pages\/1419\/revisions\/3414"}],"wp:attachment":[{"href":"https:\/\/www.lewithin.com\/fr\/wp-json\/wp\/v2\/media?parent=1419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}